{"id":5838,"date":"2023-03-07T17:03:19","date_gmt":"2023-03-07T16:03:19","guid":{"rendered":"https:\/\/www.landolt-weine.ch\/cms\/?post_type=event&#038;p=5838"},"modified":"2026-04-21T14:22:05","modified_gmt":"2026-04-21T12:22:05","slug":"uncorked-die-weinexpo","status":"publish","type":"event","link":"https:\/\/www.landolt-weine.ch\/cms\/event\/uncorked-die-weinexpo\/","title":{"rendered":"Uncorked &#8211; die Weinexpo 4. &amp; 5. September 2026"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Degustieren. Entdecken. Verlieben.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am Freitag, 4. und Samstag 5. April entkorken wir zahlreiche Weine \u2013 komm bei uns in der Vinothek vorbei und degustiere dich durch unsere vielf\u00e4ltige Weinwelt. <\/p>\n","protected":false},"featured_media":8026,"template":"","class_list":["post-5838","event","type-event","status-publish","has-post-thumbnail","hentry"],"acf":{"leadtext":"","inhaltselemente":[{"acf_fc_layout":"image","image":8651,"image_margin":"margin-after-big"},{"acf_fc_layout":"image_text","image_text_titel":"Degustiere Dich durch die Landolt Weinwelt...","image_text_titel_typ":"h2__section-title","image_text_titel_fake":false,"image_text_subtitle":"4. und 5. September 2026","image_text_link":"","image_text_content":"<p>Nach der Fr\u00fchlings-Edition geht unsere UNCORKED Weinexpo in die n\u00e4chste Runde.<\/p>\n<p>F\u00fcr zwei Tage wird die Vinothek erneut zur entspannten Genusszone \u2013 mit Lieblingsweinen, neuen Entdeckungen und ganz viel \u00abnoch ein Glas\u00bb-Gef\u00fchl.<\/p>\n","image_text_text_as_lead":false,"image_text_bild":8653,"image_text_video":"","image_text_position_bild":"left","image_text_margin":"margin-after-default"},{"acf_fc_layout":"image_text","image_text_titel":"","image_text_titel_typ":"h2__section-title","image_text_titel_fake":false,"image_text_subtitle":"","image_text_link":"","image_text_content":"<p><strong>Was Dich erwartet<\/strong><\/p>\n<p>Zahlreiche Weine aus unserem Sortiment stehen f\u00fcr Dich bereit \u2013 von bew\u00e4hrten Klassikern bis hin zu spannenden Neuank\u00f6mmlingen. Entdecke unsere Weinwelt in Deinem Tempo, vergleiche und finde die Flaschen, die Dich begeistern.<br \/>\nUnser Landolt Team begleitet Dich mit ehrlichen Empfehlungen, spannenden Geschichten rund um Weingut und Winzer und nat\u00fcrlich einer grossen Portion Leidenschaft f\u00fcr Wein.<\/p>\n<p data-start=\"869\" data-end=\"894\"><strong>F\u00fcr wen ist UNCORKED?<br \/>\n<\/strong>F\u00fcr alle. Ob Weinkennerin, neugieriger Entdecker oder einfach Genussmensch \u2013 bei UNCORKED geht es um das Wein-Philosophieren, sondern um sympathische Freude am Genuss eines guten Glases.<\/p>\n<p data-start=\"1059\" data-end=\"1080\"><strong>Das gewisse Extra<br \/>\n<\/strong>Neben ganz viel Genuss profitierst Du w\u00e4hrend der Messe von attraktiven Staffelrabatten auf unser gesamtes Landolt Sortiment*.<\/p>\n","image_text_text_as_lead":false,"image_text_bild":8535,"image_text_video":"","image_text_position_bild":"right","image_text_margin":"margin-after-big"},{"acf_fc_layout":"einspalter_text","einspalter_text_titel":"Vorbeischauen, geniessen und profitieren!","einspalter_text_titel_typ":"2","einspalter_text_titel_fake":false,"einspalter_text_content":"<p><strong>Wann:<br \/>\n<\/strong>Freitag, 4. September, ab 14.00 \u2013 20.00 Uhr<br \/>\nSamstag, 5. September, ab 14.00 \u2013 20.00 Uhr<\/p>\n<p><strong><b>Eintritt: <\/b><\/strong>Kosten: 20.\u2013 CHF pro Person<\/p>\n<p><a class=\"btn btn-primary\" href=\"https:\/\/www.landolt-weine.ch\/uncorked-september-2026\/00009987\"><span class=\"s1\">Hier Dein Ticket kaufen<\/span><\/a><\/p>\n<p>Wo: In der Landolt Vinothek, Uetlibergstrasse 130, 8045 Z\u00fcrich<\/p>\n","einspalter_text_margin":"margin-after-big"},{"acf_fc_layout":"image","image":8655,"image_margin":"margin-after-default"},{"acf_fc_layout":"einspalter_text","einspalter_text_titel":"Foto- und Videoaufnahmen bei unseren Events","einspalter_text_titel_typ":"3","einspalter_text_titel_fake":false,"einspalter_text_content":"<p>Um die besonderen Momente unserer Events festzuhalten, nehmen wir hin und wieder Fotos und Videos auf. Diese k\u00f6nnen f\u00fcr unsere Werbung genutzt werden, z. B. in Werbevideos, Social-Media-Posts oder Printmaterialien. Deine Privatsph\u00e4re ist uns wichtig! Falls du nicht m\u00f6chtest, dass Aufnahmen von dir ver\u00f6ffentlicht werden, sag einfach unserem Fotografen oder dem Filmteam vor Ort Bescheid.<\/p>\n","einspalter_text_margin":"margin-after-big"}]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uncorked - die Weinexpo 4. &amp; 5. September 2026 - Landolt Weine<\/title>\n<meta name=\"description\" content=\"Degustiere dich durch unsere facettenreiche Weinwelt und entdecke neue Lieblingsweine.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.landolt-weine.ch\/cms\/event\/uncorked-die-weinexpo\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uncorked - die Weinexpo 4. &amp; 5. September 2026 - Landolt Weine\" \/>\n<meta property=\"og:description\" content=\"Degustiere dich durch unsere facettenreiche Weinwelt und entdecke neue Lieblingsweine.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.landolt-weine.ch\/cms\/event\/uncorked-die-weinexpo\/\" \/>\n<meta property=\"og:site_name\" content=\"Landolt Weine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/landoltweine\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-21T12:22:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.landolt-weine.ch\/cms\/wp-content\/uploads\/2023\/03\/uncorked_weinmesse_august.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1252\" \/>\n\t<meta property=\"og:image:height\" content=\"1360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.landolt-weine.ch\\\/cms\\\/event\\\/uncorked-die-weinexpo\\\/\",\"url\":\"https:\\\/\\\/www.landolt-weine.ch\\\/cms\\\/event\\\/uncorked-die-weinexpo\\\/\",\"name\":\"Uncorked - die Weinexpo 4. &amp; 5. September 2026 - Landolt Weine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.landolt-weine.ch\\\/cms\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.landolt-weine.ch\\\/cms\\\/event\\\/uncorked-die-weinexpo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.landolt-weine.ch\\\/cms\\\/event\\\/uncorked-die-weinexpo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.landolt-weine.ch\\\/cms\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/uncorked_weinmesse_august.jpg\",\"datePublished\":\"2023-03-07T16:03:19+00:00\",\"dateModified\":\"2026-04-21T12:22:05+00:00\",\"description\":\"Degustiere dich durch unsere facettenreiche Weinwelt und entdecke neue Lieblingsweine.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.landolt-weine.ch\\\/cms\\\/event\\\/uncorked-die-weinexpo\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.landolt-weine.ch\\\/cms\\\/event\\\/uncorked-die-weinexpo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/www.landolt-weine.ch\\\/cms\\\/event\\\/uncorked-die-weinexpo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.landolt-weine.ch\\\/cms\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/uncorked_weinmesse_august.jpg\",\"contentUrl\":\"https:\\\/\\\/www.landolt-weine.ch\\\/cms\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/uncorked_weinmesse_august.jpg\",\"width\":1252,\"height\":1360,\"caption\":\"Landolt Weine - Uncorked Weinmesse\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.landolt-weine.ch\\\/cms\\\/event\\\/uncorked-die-weinexpo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.landolt-weine.ch\\\/cms\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/www.landolt-weine.ch\\\/cms\\\/event\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Uncorked &#8211; die Weinexpo 4. &amp; 5. September 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.landolt-weine.ch\\\/cms\\\/#website\",\"url\":\"https:\\\/\\\/www.landolt-weine.ch\\\/cms\\\/\",\"name\":\"Landolt Weine\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.landolt-weine.ch\\\/cms\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.landolt-weine.ch\\\/cms\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.landolt-weine.ch\\\/cms\\\/#organization\",\"name\":\"Landolt Weine\",\"url\":\"https:\\\/\\\/www.landolt-weine.ch\\\/cms\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/www.landolt-weine.ch\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.landolt-weine.ch\\\/cms\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/landolt-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.landolt-weine.ch\\\/cms\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/landolt-logo.png\",\"width\":1000,\"height\":240,\"caption\":\"Landolt Weine\"},\"image\":{\"@id\":\"https:\\\/\\\/www.landolt-weine.ch\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/landoltweine\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uncorked - die Weinexpo 4. &amp; 5. September 2026 - Landolt Weine","description":"Degustiere dich durch unsere facettenreiche Weinwelt und entdecke neue Lieblingsweine.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.landolt-weine.ch\/cms\/event\/uncorked-die-weinexpo\/","og_locale":"de_DE","og_type":"article","og_title":"Uncorked - die Weinexpo 4. &amp; 5. September 2026 - Landolt Weine","og_description":"Degustiere dich durch unsere facettenreiche Weinwelt und entdecke neue Lieblingsweine.","og_url":"https:\/\/www.landolt-weine.ch\/cms\/event\/uncorked-die-weinexpo\/","og_site_name":"Landolt Weine","article_publisher":"https:\/\/www.facebook.com\/landoltweine\/","article_modified_time":"2026-04-21T12:22:05+00:00","og_image":[{"width":1252,"height":1360,"url":"https:\/\/www.landolt-weine.ch\/cms\/wp-content\/uploads\/2023\/03\/uncorked_weinmesse_august.jpg","type":"image\/jpeg"}],"twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.landolt-weine.ch\/cms\/event\/uncorked-die-weinexpo\/","url":"https:\/\/www.landolt-weine.ch\/cms\/event\/uncorked-die-weinexpo\/","name":"Uncorked - die Weinexpo 4. &amp; 5. September 2026 - Landolt Weine","isPartOf":{"@id":"https:\/\/www.landolt-weine.ch\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.landolt-weine.ch\/cms\/event\/uncorked-die-weinexpo\/#primaryimage"},"image":{"@id":"https:\/\/www.landolt-weine.ch\/cms\/event\/uncorked-die-weinexpo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.landolt-weine.ch\/cms\/wp-content\/uploads\/2023\/03\/uncorked_weinmesse_august.jpg","datePublished":"2023-03-07T16:03:19+00:00","dateModified":"2026-04-21T12:22:05+00:00","description":"Degustiere dich durch unsere facettenreiche Weinwelt und entdecke neue Lieblingsweine.","breadcrumb":{"@id":"https:\/\/www.landolt-weine.ch\/cms\/event\/uncorked-die-weinexpo\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.landolt-weine.ch\/cms\/event\/uncorked-die-weinexpo\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/www.landolt-weine.ch\/cms\/event\/uncorked-die-weinexpo\/#primaryimage","url":"https:\/\/www.landolt-weine.ch\/cms\/wp-content\/uploads\/2023\/03\/uncorked_weinmesse_august.jpg","contentUrl":"https:\/\/www.landolt-weine.ch\/cms\/wp-content\/uploads\/2023\/03\/uncorked_weinmesse_august.jpg","width":1252,"height":1360,"caption":"Landolt Weine - Uncorked Weinmesse"},{"@type":"BreadcrumbList","@id":"https:\/\/www.landolt-weine.ch\/cms\/event\/uncorked-die-weinexpo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.landolt-weine.ch\/cms\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/www.landolt-weine.ch\/cms\/event\/"},{"@type":"ListItem","position":3,"name":"Uncorked &#8211; die Weinexpo 4. &amp; 5. September 2026"}]},{"@type":"WebSite","@id":"https:\/\/www.landolt-weine.ch\/cms\/#website","url":"https:\/\/www.landolt-weine.ch\/cms\/","name":"Landolt Weine","description":"","publisher":{"@id":"https:\/\/www.landolt-weine.ch\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.landolt-weine.ch\/cms\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Organization","@id":"https:\/\/www.landolt-weine.ch\/cms\/#organization","name":"Landolt Weine","url":"https:\/\/www.landolt-weine.ch\/cms\/","logo":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/www.landolt-weine.ch\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/www.landolt-weine.ch\/cms\/wp-content\/uploads\/2021\/01\/landolt-logo.png","contentUrl":"https:\/\/www.landolt-weine.ch\/cms\/wp-content\/uploads\/2021\/01\/landolt-logo.png","width":1000,"height":240,"caption":"Landolt Weine"},"image":{"@id":"https:\/\/www.landolt-weine.ch\/cms\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/landoltweine\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.landolt-weine.ch\/cms\/wp-json\/wp\/v2\/event\/5838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.landolt-weine.ch\/cms\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.landolt-weine.ch\/cms\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.landolt-weine.ch\/cms\/wp-json\/wp\/v2\/media\/8026"}],"wp:attachment":[{"href":"https:\/\/www.landolt-weine.ch\/cms\/wp-json\/wp\/v2\/media?parent=5838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}